{"id":10005150,"date":"2026-05-06T16:24:15","date_gmt":"2026-05-06T14:24:15","guid":{"rendered":"https:\/\/www.ovronnaz.ch\/events\/\/"},"modified":"2026-05-06T16:24:15","modified_gmt":"2026-05-06T14:24:15","slug":"yoga-sous-les-melezes-4","status":"publish","type":"tribe_events","link":"https:\/\/www.ovronnaz.ch\/de\/event\/yoga-sous-les-melezes-4\/2026-08-12\/","title":{"rendered":"Yoga unter L\u00e4rchen"},"content":{"rendered":"<h1>Yoga unter L\u00e4rchen<\/h1>\n<h3>Jeden Mittwochvormittag von 9 bis 11 Uhr<br \/>\nvom 1. Juli bis 26. August 2026<\/h3>\n<p>Nehmen Sie an einer Yoga-Einf\u00fchrung im Freien teil, umgeben von der beruhigenden Natur einer L\u00e4rchenlichtung.<br \/>\nDiese Praxis erm\u00f6glicht es Ihnen, wieder zu sich selbst zu finden und gleichzeitig die belebende Energie des Waldes zu genie\u00dfen.<br \/>\nEin erholsames Erlebnis, das Entspannung, Wohlbefinden und Harmonie mit der Natur vereint.<\/p>\n<p>Einf\u00fchrung f\u00fcr alle Niveaus, Yogamatten stehen in Jorasse zur Verf\u00fcgung.<\/p>\n<p>Treffpunkt an der Talstation der Sesselbahn Jorasse<br \/>\nDie Kosten f\u00fcr die Sesselbahn gehen zu Lasten der Teilnehmer.<\/p>\n<p>Im Aktivit\u00e4tspass inbegriffen oder 10 CHF<br \/>\nab 15 Jahren<br \/>\nAnmeldung bis 16 Uhr am Vortag erforderlich, begrenzte Teilnehmerzahl<br \/>\n<strong>Office du Tourisme d\u2019Ovronnaz<br \/>\n<\/strong><i class=\"fa fa-phone \"><\/i><a href=\"tel:+41 (0)27 306 42 93\" target=\"_blank\" rel=\"noopener noreferrer\">+41(0)27\/306.42.93&nbsp;<\/a> <i class=\"fa fa-envelope-o \"><\/i><br \/>\n<a href=\"mailto:info@ovronnaz.ch\" target=\"_blank\" rel=\"noopener noreferrer\">info@ovronnaz.ch<\/a><\/p>\n<p><img decoding=\"async\" class=\"alignnone  wp-image-29714\" src=\"https:\/\/www.ovronnaz.ch\/wp-content\/uploads\/2023\/07\/Yoga-AC-1-3-scaled-1.jpg\" alt=\"\" width=\"777\" height=\"583\" srcset=\"https:\/\/www.ovronnaz.ch\/wp-content\/uploads\/2023\/07\/Yoga-AC-1-3-scaled-1-1280x960.jpg 1280w, https:\/\/www.ovronnaz.ch\/wp-content\/uploads\/2023\/07\/Yoga-AC-1-3-scaled-1-980x735.jpg 980w, https:\/\/www.ovronnaz.ch\/wp-content\/uploads\/2023\/07\/Yoga-AC-1-3-scaled-1-480x360.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) and (max-width: 1280px) 1280px, 100vw\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Einf\u00fchrung in das Yoga im Freien, in einer erholsamen Umgebung inmitten von L\u00e4rchen. <\/p>\n","protected":false},"author":1,"featured_media":45990,"template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_monsterinsights_skip_tracking":false,"_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":""},"tags":[],"tribe_events_cat":[68,106],"class_list":["post-10005150","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tribe_events_cat-automnale","tribe_events_cat-office-du-tourisme","cat_automnale","cat_office-du-tourisme","tribe-recurring-event","tribe-recurring-event-parent"],"_links":{"self":[{"href":"https:\/\/www.ovronnaz.ch\/de\/wp-json\/wp\/v2\/tribe_events\/10005150","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ovronnaz.ch\/de\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/www.ovronnaz.ch\/de\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/www.ovronnaz.ch\/de\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/www.ovronnaz.ch\/de\/wp-json\/wp\/v2\/tribe_events\/10005150\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ovronnaz.ch\/de\/wp-json\/wp\/v2\/media\/45990"}],"wp:attachment":[{"href":"https:\/\/www.ovronnaz.ch\/de\/wp-json\/wp\/v2\/media?parent=10005150"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ovronnaz.ch\/de\/wp-json\/wp\/v2\/tags?post=10005150"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/www.ovronnaz.ch\/de\/wp-json\/wp\/v2\/tribe_events_cat?post=10005150"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}