{"id":10002985,"date":"2026-05-08T14:24:34","date_gmt":"2026-05-08T12:24:34","guid":{"rendered":"https:\/\/www.ovronnaz.ch\/events\/decouverte-de-la-fromagerie-dodonne\/"},"modified":"2026-05-08T15:13:23","modified_gmt":"2026-05-08T13:13:23","slug":"decouverte-de-la-fromagerie-dodonne-3-2","status":"publish","type":"tribe_events","link":"https:\/\/www.ovronnaz.ch\/de\/event\/decouverte-de-la-fromagerie-dodonne-3-2\/2026-07-03\/","title":{"rendered":"Entdecken Sie die K\u00e4serei von Odonne"},"content":{"rendered":"<h2>Entdecken Sie die K\u00e4serei von Odonne<\/h2>\n<h5><span style=\"color: #666666; font-size: 14px;\">jeden Freitagnachmittag von 14 bis 15 Uhr<br \/>\nvom 3. Juli bis 28. August 2026<\/span><\/h5>\n<p>Seit letztem Sommer wurde die K\u00e4serei von Odonne renoviert. Lernen Sie das engagierte Team kennen, das dort arbeitet, und genie\u00dfen Sie eine k\u00f6stliche Verkostung.<\/p>\n<p>Treffpunkt an der Alpage d&#8217;Odonne (ca. 1 Stunde Fu\u00dfweg vom Sportzentrum oder vom Gipfel des Jorasse).<\/p>\n<p>Ab 5 Jahren<\/p>\n<p>Im Aktivit\u00e4tspass inbegriffen oder 15 CHF<br \/>\nAnmeldung bis 16 Uhr am Vortag erforderlich, begrenzte Teilnehmerzahl<\/p>\n<p><strong>Tourismusb\u00fcro Ovronnaz<\/strong><br \/>\n<a href=\"tel:+41 (0)27 306 42 93\" target=\"_blank\" rel=\"noopener noreferrer\">+41(0)27\/306.42.93<\/a><br \/>\n<i class=\"fa fa-envelope-o \"><\/i><a href=\"mailto:info@ovronnaz.ch\" target=\"_blank\" rel=\"noopener noreferrer\">info@ovronnaz.ch<\/a><\/p>\n<h2><img decoding=\"async\" class=\"alignnone wp-image-38856\" src=\"https:\/\/www.ovronnaz.ch\/wp-content\/uploads\/2024\/04\/fromagerie.jpg\" alt=\"\" width=\"837\" height=\"557\" \/><\/h2>\n","protected":false},"excerpt":{"rendered":"<p>Besichtigung der K\u00e4serei von Odonne.<\/p>\n","protected":false},"author":1,"featured_media":46008,"template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":""},"tags":[],"tribe_events_cat":[64,106],"class_list":["post-10002985","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tribe_events_cat-estivales","tribe_events_cat-office-du-tourisme","cat_estivales","cat_office-du-tourisme","tribe-recurring-event","tribe-recurring-event-parent"],"_links":{"self":[{"href":"https:\/\/www.ovronnaz.ch\/de\/wp-json\/wp\/v2\/tribe_events\/10002985","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ovronnaz.ch\/de\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/www.ovronnaz.ch\/de\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/www.ovronnaz.ch\/de\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/www.ovronnaz.ch\/de\/wp-json\/wp\/v2\/tribe_events\/10002985\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ovronnaz.ch\/de\/wp-json\/wp\/v2\/media\/46008"}],"wp:attachment":[{"href":"https:\/\/www.ovronnaz.ch\/de\/wp-json\/wp\/v2\/media?parent=10002985"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ovronnaz.ch\/de\/wp-json\/wp\/v2\/tags?post=10002985"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/www.ovronnaz.ch\/de\/wp-json\/wp\/v2\/tribe_events_cat?post=10002985"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}