{"id":10001105,"date":"2023-11-02T15:05:18","date_gmt":"2023-11-02T14:05:18","guid":{"rendered":"http:\/\/www.ovronnaz.ch\/tribe_events\/\/"},"modified":"2023-11-14T12:30:57","modified_gmt":"2023-11-14T11:30:57","slug":"atelier-conte","status":"publish","type":"tribe_events","link":"https:\/\/www.ovronnaz.ch\/de\/event\/atelier-conte\/2024-03-19\/","title":{"rendered":"Workshop M\u00e4rchen"},"content":{"rendered":"<h1 class=\"_04xlpA direction-ltr align-center para-style-body\">Workshop M\u00e4rchen<\/h1>\n<div dir=\"ltr\">\n<div dir=\"ltr\">\n<p class=\"_04xlpA direction-ltr align-justify para-style-body\">In diesem Workshop werden <strong>sprachliche und k\u00f6rperliche Aktivit\u00e4ten rund um ein M\u00e4rchen angeboten<\/strong>, die den stimmlichen und k\u00f6rperlichen Ausdruck f\u00f6rdern.<\/p>\n<p>Komm und am\u00fcsiere dich mit Fr\u00e9d\u00e9rique aus dem Atelier La Main L\u00e9g\u00e8re.<\/p>\n<p>https:\/\/www.lamainlegere.ch\/<\/p>\n<p><strong>Dienstags vom 26.12.2023 bis zum 9.04.2024 von 14h bis 16h.<\/strong><\/p>\n<p><em>Treffpunkt ist das Tourismusb\u00fcro.<\/em><\/p>\n<p><strong>F\u00fcr Kinder von 3 bis 12 Jahren <\/strong><\/p>\n<p><em>5 CHF &#8211; Kostenlos mit dem Aktivit\u00e4ten-Pass f\u00fcr G\u00e4ste, f\u00fcr R2 und Einwohner.<\/em><\/p>\n<p><strong>Anmeldung bis 16 Uhr am Vortag erforderlich, begrenzte Pl\u00e4tze<\/strong><\/p>\n<\/div>\n<\/div>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-36314\" src=\"http:\/\/www.ovronnaz.ch\/wp-content\/uploads\/2023\/11\/contes-e1698932404960.png\" alt=\"\" width=\"1080\" height=\"838\" srcset=\"https:\/\/www.ovronnaz.ch\/wp-content\/uploads\/2023\/11\/contes-e1698932404960.png 1080w, https:\/\/www.ovronnaz.ch\/wp-content\/uploads\/2023\/11\/contes-e1698932404960-300x233.png 300w, https:\/\/www.ovronnaz.ch\/wp-content\/uploads\/2023\/11\/contes-e1698932404960-1024x795.png 1024w, https:\/\/www.ovronnaz.ch\/wp-content\/uploads\/2023\/11\/contes-e1698932404960-768x596.png 768w, https:\/\/www.ovronnaz.ch\/wp-content\/uploads\/2023\/11\/contes-e1698932404960-480x372.png 480w, https:\/\/www.ovronnaz.ch\/wp-content\/uploads\/2023\/11\/contes-e1698932404960-980x760.png 980w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dieser Workshop bietet sprachliche und k\u00f6rperliche Aktivit\u00e4ten rund um ein M\u00e4rchen an<\/p>\n","protected":false},"author":1,"featured_media":36314,"template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_monsterinsights_skip_tracking":false,"_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":""},"tags":[],"tribe_events_cat":[65,106],"class_list":["post-10001105","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tribe_events_cat-hivernale","tribe_events_cat-office-du-tourisme","cat_hivernale","cat_office-du-tourisme","tribe-recurring-event","tribe-recurring-event-parent"],"_links":{"self":[{"href":"https:\/\/www.ovronnaz.ch\/de\/wp-json\/wp\/v2\/tribe_events\/10001105","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ovronnaz.ch\/de\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/www.ovronnaz.ch\/de\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/www.ovronnaz.ch\/de\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/www.ovronnaz.ch\/de\/wp-json\/wp\/v2\/tribe_events\/10001105\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ovronnaz.ch\/de\/wp-json\/wp\/v2\/media\/36314"}],"wp:attachment":[{"href":"https:\/\/www.ovronnaz.ch\/de\/wp-json\/wp\/v2\/media?parent=10001105"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ovronnaz.ch\/de\/wp-json\/wp\/v2\/tags?post=10001105"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/www.ovronnaz.ch\/de\/wp-json\/wp\/v2\/tribe_events_cat?post=10001105"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}